{"id":12377,"date":"2025-07-23T23:01:40","date_gmt":"2025-07-23T23:01:40","guid":{"rendered":"https:\/\/fv6qoy3ls0.wpdns.site\/produto\/nisi-v7-kit-starter-100mm\/"},"modified":"2026-07-07T12:23:48","modified_gmt":"2026-07-07T11:23:48","slug":"nisi-v7-kit-starter-100mm","status":"publish","type":"product","link":"https:\/\/hi-techwonder.com\/es\/producto\/nisi-v7-kit-starter-100mm\/","title":{"rendered":"NiSi V7 Kit Starter 100mm"},"content":{"rendered":"<h3>Nisi V7 Kit Starter 100mm<\/h3>\n<p>O NiSi 100mm V7 Starter Kit \u00e9 um kit de inicia\u00e7\u00e3o de grande valor para fot\u00f3grafos de paisagens e paisagens marinhas com tudo o que precisa para come\u00e7ar. \u00c9 perfeito para quem quer criar imagens de longa exposi\u00e7\u00e3o e usar filtros ND e filtros GND com v\u00e1rias objectivas at\u00e9 82mm com uma rosca de filtro padr\u00e3o. O kit inclui os an\u00e9is adaptadores mais populares (67mm, 72mm, 77mm e 82mm) com outros vendidos separadamente. O NiSi 100mm V7 Starter Kit representa uma grande poupan\u00e7a em compara\u00e7\u00e3o com a compra de todos os itens inclu\u00eddos separadamente.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-26983\" src=\"https:\/\/hi-techwonder.com\/wp-content\/themes\/woodmart\/images\/lazy.svg\" data-src=\"https:\/\/nisioptics.pt\/wp-content\/uploads\/2022\/03\/V7-starter-kit-1-e1697642821887-1024x678.jpg\" alt=\"\" width=\"752\" height=\"498\"><\/p>\n<h4>Porta-Filtros V7 100mm<\/h4>\n<p>O porta-filtros NiSi V7 100mm com True Color NC CPL e tampa de lente \u00e9 o mais avan\u00e7ado suporte de filtros de 100mm que j\u00e1 cri\u00e1mos, com um design refinado com base no feedback dos fot\u00f3grafos. O V7 permite a f\u00e1cil utiliza\u00e7\u00e3o de at\u00e9 tr\u00eas filtros de 100mm de largura e 2mm de espessura, juntamente com um novo filtro polarizador circular True Color da NiSi, e n\u00e3o tem vinheta a 16mm com lentes grande angular em full-frame.<\/p>\n<p>\u00c9 fabricado em alum\u00ednio de qualidade aeron\u00e1utica com processamento de elemento \u00fanico por m\u00e1quina CNC, e o acabamento preto mate fosco na superf\u00edcie minimiza os reflexos. O V7 possui um design de roda de rota\u00e7\u00e3o \u00fanico, pelo que o filtro CPL pode ser rodado independentemente com os filtros ainda no lugar atrav\u00e9s de uma engrenagem na parte de tr\u00e1s do suporte de filtro.<\/p>\n<p>Esta vers\u00e3o do V7 inclui o nov\u00edssimo CPL True Color, que evita o tom amarelo introduzido pela maioria dos CPLs.<\/p>\n<p>O nosso novo design CPL Ponto a Ponto permite uma instala\u00e7\u00e3o guiada mais f\u00e1cil do CPL no adaptador principal de 82 mm. Alinhando as marcas brancas no CPL com a marca branca no adaptador principal e torcendo, pode facilmente fixar o CPL no lugar e remov\u00ea-lo com pouco esfor\u00e7o.<\/p>\n<p>A utiliza\u00e7\u00e3o do Suporte de Filtro NiSi V7 100mm pode ser facilmente realizada aparafusando primeiro o anel adaptador de 82mm inclu\u00eddo numa objetiva com rosca de filtro frontal de 82mm. Os an\u00e9is step-up inclu\u00eddos s\u00e3o: 67mm, 72mm e 77mm.<\/p>\n<p>Depois de encaixado no anel adaptador, o pino de bloqueio de puxar e soltar do suporte do filtro ajuda a proporcionar uma liga\u00e7\u00e3o fi\u00e1vel que permite que o suporte seja rodado 360\u00b0. Para fixar ainda mais a posi\u00e7\u00e3o do suporte do filtro, este possui um bloqueio que pode ser ativado rodando uma pequena roda em torno do pino de liberta\u00e7\u00e3o, o que impede qualquer rota\u00e7\u00e3o do suporte do filtro.<\/p>\n<h3>Filtro ND<\/h3>\n<p>Um filtro de densidade neutra (ND) que reduz uniformemente a quantidade de luz que entra na objetiva. Os filtros ND podem permitir uma maior desfocagem de movimento e detalhes de imagem, permitindo uma grande abertura e uma velocidade de obtura\u00e7\u00e3o lenta. Tamb\u00e9m s\u00e3o \u00fateis quando o contraste entre as luzes e as sombras \u00e9 demasiado elevado para obter uma exposi\u00e7\u00e3o de qualidade.<\/p>\n<ul>\n<li>O filtro ND1000 de 10 stops \u00e9 utilizado durante o dia, fora da hora dourada, uma vez que a luz ambiente intensa requer muito mais &#8220;bloqueio de luz&#8221;. Estes filtros podem prolongar a exposi\u00e7\u00e3o at\u00e9 5 minutos durante a hora dourada com as defini\u00e7\u00f5es correctas.<\/li>\n<\/ul>\n<p>Os filtros NiSi ND n\u00e3o afectam a colora\u00e7\u00e3o da imagem, proporcionam cores reais e s\u00e3o feitos de vidro \u00f3tico de alta qualidade (n\u00e3o de resina) com nano-revestimento para que n\u00e3o se perca nenhum detalhe. Quando se utilizam filtros de densidade neutra, a c\u00e2mara \u00e9 vulner\u00e1vel \u00e0 luz infravermelha, que ir\u00e1 lan\u00e7ar a cor vermelha indesejada nas fotografias quando se fotografa com uma pequena abertura. T\u00eam uma camada de prote\u00e7\u00e3o contra infravermelhos para eliminar a luz infravermelha atrav\u00e9s da objetiva e restaurar a cor natural.<\/p>\n<h4>Filtros GND<\/h4>\n<p>O filtro de densidade neutra graduado Medium(3 stops) \u00e9 um filtro retangular que ajuda a escurecer \u00e1reas espec\u00edficas de uma imagem, como c\u00e9us brilhantes, enquanto permite uma exposi\u00e7\u00e3o normal e n\u00e3o afetada nas outras regi\u00f5es da imagem. O filtro \u00e9 mais denso na extremidade e torna-se mais claro no centro, com uma linha de transi\u00e7\u00e3o a meio da extremidade entre as \u00e1reas densas e claras.<\/p>\n<p>Um filtro de densidade neutra com uma linha de transi\u00e7\u00e3o a meio da margem \u00e9 especialmente \u00fatil para imagens que apresentam edif\u00edcios, pequenas montanhas e outros elementos que sobressaem acima da linha do horizonte. A zona de transi\u00e7\u00e3o de um filtro de densidade neutra m\u00e9dia \u00e9 40% mais pequena do que a de um filtro de densidade neutra graduada suave e \u00e9 ideal para fotografar ao nascer e ao p\u00f4r do sol.<\/p>\n<h4>Estojo Caddy para Filtros 100mm<\/h4>\n<p>O Estojo para Filtros NiSi Caddy 100mm para 9 Filtros foi concebido para os filtros do sistema NiSi 100mm e tem capacidade para 4 x 100x100mm e 5 x 100x150mm. Possui uma al\u00e7a ajust\u00e1vel para o corpo e pode ser transportada como uma bolsa de ombro, bolsa de tiracolo ou bolsa de cintura. Pode ser convenientemente montada numa perna de trip\u00e9 para f\u00e1cil acesso e utiliza\u00e7\u00e3o e foi concebida a partir de um material leve que protege os seus filtros de riscos. A bolsa pode conter at\u00e9 9 filtros na combina\u00e7\u00e3o 4 x 100x100mm e 5 x 100x150mm e possui um design flip-top para manter a bolsa aberta quando em uso.<\/p>\n<p>O estojo NiSi Caddy 100mm tamb\u00e9m pode conter um suporte NiSi 100mm V7 na primeira ranhura da bolsa (reduzindo as ranhuras de filtro para 8).<\/p>\n<p>O estojo \u00e9 muito leve, pesa 350g e \u00e9 suficientemente pequeno para caber na maioria das bolsas de c\u00e2maras. As dimens\u00f5es f\u00edsicas s\u00e3o: 19cm x 13,5cm x 8cm.<\/p>\n<p>Saiba mais sobre o nosso sistema de <a href=\"https:\/\/nisioptics.pt\/categoria\/descobre\/descubre-sistema-100m\/\" target=\"_blank\" rel=\"noopener\">100mm.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Inclui o novo suporte NiSi V7<\/li>\n<li>Inclui o novo CPL True Color e adaptadores para 67mm, 72, 77mm e 82mm<\/li>\n<li>O suporte permite a utiliza\u00e7\u00e3o de 3 filtros quadrados + 1 polarizador circular<\/li>\n<li>Sem vinheta a 16mm (Full Frame)<\/li>\n<li>Inclui dois filtros: 100x100mm IR ND1000 10 Stop ND e 100x150mm IR GND8 Medium 3 Stop<\/li>\n<li>Inclui a bolsa NiSi Caddy, a tampa da objetiva, o Clever Cleaner, o pano de limpeza e o ventilador<\/li>\n<li>Kit de inicia\u00e7\u00e3o de grande valor para come\u00e7ar a utilizar filtros ND e fotografia de paisagem<\/li>\n<\/ul>\n","protected":false},"featured_media":9365,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[2543],"product_cat":[1058],"product_tag":[],"class_list":["post-12377","product","type-product","status-publish","has-post-thumbnail","product_brand-nisioptics-es","product_cat-filtros-100mm-es","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":2,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"_links":{"self":[{"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/product\/12377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/comments?post=12377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/media\/9365"}],"wp:attachment":[{"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/media?parent=12377"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/product_brand?post=12377"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/product_cat?post=12377"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hi-techwonder.com\/es\/wp-json\/wp\/v2\/product_tag?post=12377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}